{"id":37755,"date":"2022-07-21T09:10:22","date_gmt":"2022-07-21T09:10:22","guid":{"rendered":"https:\/\/drlesliekorn.com\/acerca-de-mi\/plano-de-brainbow\/"},"modified":"2025-01-10T12:31:42","modified_gmt":"2025-01-10T12:31:42","slug":"modelo-arcoiris-cerebro","status":"publish","type":"page","link":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/","title":{"rendered":"Plano de Brainbow"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull brainbow-banner-sec has-background\" style=\"background-color:#eae1d5\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"circle-mapping\">\n<div class=\"brainbowCircle\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/09\/spanB.png\" alt=\"El Modelo del arcoiris del cerebro\"\/><\/div>\n<div class=\"brainbowCircle forMob\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/09\/BBB_espanol.png\" alt=\"El Modelo del arcoiris del cerebro\"\/><\/div>\n\n<h2 class=\"mobHead\">El Modelo del arcoiris del cerebro<\/h2>\n\n<div class=\"innerSection no1\">\n<div class=\"innerBox\">Bioindividualidad<\/div>\n<div class=\"onHover-display\">Teniendo en cuenta tu <b>bioindividualidad<\/b>, analizo tu biolog\u00eda, tu gen\u00f3mica y el entorno ambiental y cultural que han conformado tu salud, para as\u00ed desarrollar un enfoque de precisi\u00f3n que esclarezca tus necesidades nutricionales, y tus v\u00edas metab\u00f3licas y de desintoxicaci\u00f3n. Este importante primer paso me permite afinar y personalizar otras intervenciones que elijas.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no2\">\n<div class=\"innerBox\">Estrategias de adherencia<\/div>\n<div class=\"onHover-display\">Incluso el mejor programa de salud y autocuidado no funcionar\u00e1 si no se practica con constancia. Con las <b>estrategias de adherencia<\/b>, te proporciono m\u00e9todos para ayudarte a afrontar las 5 barreras ante el cambio de un modo centrado, desenfadado y sin pena.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no3\">\n<div class=\"innerBox\">Estados alterados<\/div>\n<div class=\"onHover-display\">Los <b>estados alterados<\/b> implican abrazar nuestras capacidades naturales para alterar nuestra conciencia con fines sanadores, al mismo tiempo que reducimos las formas en que podr\u00edamos automedicarnos y que nos conducen a efectos secundarios no deseados. Un m\u00e9todo potente para mejorar la depresi\u00f3n, el trastorno de estr\u00e9s postraum\u00e1tico, la ansiedad y la p\u00e9rdida de esperanza es el uso guiado y cuidadoso de plantas o medicamentos como los psicod\u00e9licos, que alteran la conciencia y mejoran la autorregulaci\u00f3n. Yo puedo evaluar si eres candidato para alguna variedad de estos m\u00e9todos.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no4\">\n<div class=\"innerBox\">Espiritualidad<\/div>\n<div class=\"onHover-display\">En cualquier forma que te parezca adecuada, la <b>espiritualidad<\/b> te puede ayudar a darle sentido a tu vida, encontrar tu prop\u00f3sito y catalizar un cambio profundo. Yo puedo ayudarte a explorar el poder de los mitos y el arte, la sabidur\u00eda de los sue\u00f1os, la pr\u00e1ctica de la meditaci\u00f3n y la posibilidad del crecimiento postraum\u00e1tico.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no5\">\n<div class=\"innerBox\">Respiraci\u00f3n<\/div>\n<div class=\"onHover-display\">La <b>respiraci\u00f3n<\/b> es la vida misma. Los m\u00e9todos para mejorar y controlar la respiraci\u00f3n son esenciales para la salud mental y f\u00edsica. Cuando tu respiraci\u00f3n se hace consciente \u2014con\nejercicios espec\u00edficos que adapto a tus s\u00edntomas\u2014 dispones, en cualquier momento del d\u00eda, de una forma gentil pero poderosa de mejorar las condiciones de salud mental.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no6\">\n<div class=\"innerBox\">Som\u00e1tica y Trabajo Corporal<\/div>\n<div class=\"onHover-display\"><b>La som\u00e1tica y el trabajo corporal<\/b> abarcan muchos m\u00e9todos de toque terap\u00e9utico que ayudan con el sue\u00f1o, el dolor, la concentraci\u00f3n y la digesti\u00f3n. Te recomiendo m\u00e9todos que te ayudar\u00e1n a reconectar con tu cuerpo para conectarte con la tierra, energizarte y relajarte. <\/div>\n<\/div>\n\n<div class=\"innerSection no7\">\n<div class=\"innerBox\">Ejercicio<\/div>\n<div class=\"onHover-display\">El <b>ejercicio<\/b> tiene numerosos beneficios. Con tantos tipos, \u00bfc\u00f3mo saber qu\u00e9 combinaciones son las mejores para ti y tus objetivos de salud? Yo exploro tu historia con el ejercicio y utilizo la ciencia para personalizarlo conforme a tus necesidades, aliviar tus s\u00edntomas y mejorar tu estado de \u00e1nimo.<\/div>\n<\/div>\n\n<div class=\"innerSection no8\">\n<div class=\"innerBox\">Hidroterapia\/Desintoxicaci\u00f3n<\/div>\n<div class=\"onHover-display\">Con la <b>hidroterapia<\/b>, puedo ense\u00f1arte a utilizar el agua y sus diferentes temperaturas para reducir el dolor, la fatiga, la ansiedad y la depresi\u00f3n, ayudar a la digesti\u00f3n y mejorar tu funci\u00f3n cognitiva general y tu estado de \u00e1nimo. La <b>desintoxicaci\u00f3n<\/b> incluye m\u00e9todos suaves que yo personalizo seg\u00fan tus necesidades, y que ayudan a tu cuerpo y cerebro a eliminar toxinas.\n <\/div>\n<\/div>\n\n<div class=\"innerSection no9\">\n<div class=\"innerBox\">Medicina herbal<\/div>\n<div class=\"onHover-display\">Las hierbas son potentes agentes sanadores naturales. Muchas de las sustancias que contienen son la madre de los f\u00e1rmacos. Incorporar la <b>medicina herbal<\/b> a tu programa de salud es un proceso org\u00e1nico. Yo puedo sugerirte hierbas que reducen la fatiga, el dolor y el malestar digestivo, y mejoran el estado de \u00e1nimo y la concentraci\u00f3n.<\/div>\n<\/div>\n\n<div class=\"innerSection no10\">\n<div class=\"innerBox\">Suplementos<\/div>\n<div class=\"onHover-display\">La <b>suplementaci\u00f3n<\/b> aborda las deficiencias comunes de nutrientes que afectan la salud f\u00edsica y mental. Estas pueden surgir por tu nivel de estr\u00e9s, tu dieta, el uso de ciertos medicamentos o tus necesidades gen\u00e9ticas. Yo te ayudo a identificar los suplementos beneficiosos para ti, y a comprobar si hay interacciones entre medicamentos, suplementos y hierbas, para asegurarme de que recibas un apoyo \u00f3ptimo.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no11\">\n<div class=\"innerBox\">Medicina Culinaria<\/div>\n<div class=\"onHover-display\">La <b>medicina culinaria<\/b> te libera, para que puedas seguir la dieta m\u00e1s adecuada para ti, en lugar de las dietas o ideolog\u00edas de moda. Yo te ayudo a descubrir si, biol\u00f3gicamente, eres vegetariano, carn\u00edvoro o algo intermedio, y te gu\u00edo para que encuentres formas deliciosas y f\u00e1ciles de nutrirte y sanar con la comida.\n\n<\/div>\n<\/div>\n\n<div class=\"innerSection no12\">\n<div class=\"innerBox\">Digesti\u00f3n<\/div>\n<div class=\"onHover-display\">Sin duda, la <b>digesti\u00f3n<\/b> afecta a tu mente y tu estado de \u00e1nimo. Podemos incorporar diversos m\u00e9todos para sanar y optimizar el funcionamiento de tu intestino, de modo que puedas absorber los alimentos, nutrientes y hierbas que tomas, combatiendo las enfermedades digestivas cr\u00f3nicas como el s\u00edndrome de intestino irritable, la enfermedad intestinal inflamatoria, la colitis, el reflujo gastroesof\u00e1gico y otras.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no13\">\n<div class=\"innerBox\">Relaci\u00f3n Humano-Animal<\/div>\n<div class=\"onHover-display\">Las <b>relaciones de los humanos con los animales<\/b> de compa\u00f1\u00eda, de apoyo emocional y de servicio pueden contribuir a la sanaci\u00f3n de la ansiedad, el trastorno de estr\u00e9s postraum\u00e1tico y el trauma complejo. Yo te puedo ayudar a evaluar si est\u00e1s preparado para dar este paso, y apoyarte para darlo. \n<\/div>\n<\/div>\n\n<div class=\"innerSection no14\">\n<div class=\"innerBox\">Cultura<\/div>\n<div class=\"onHover-display\">En el Modelo del arcoiris del cerebro\u00ae, la <b>cultura<\/b> se refiere a los valores y pr\u00e1cticas, individuales y colectivos, que son fundamentales para la salud. Este concepto incluye el papel de la herencia \u00e9tnica y la identidad, que influye en la bioindividualidad y la gen\u00f3mica, y se extiende a todos los aspectos de la identidad personal, incluidos el sexo y el g\u00e9nero. La cultura se entrecruza con la salud como influencia protectora y resiliente, y como factor de riesgo cuando se encuentra con la discriminaci\u00f3n. La cultura conecta con la salud mental a trav\u00e9s del significado que le damos a los s\u00edntomas y el papel del trauma cultural. La cultura es la ra\u00edz de lo que somos; la ra\u00edz de la palabra cultura: cult (culto) y ura (tierra), se refiere al culto a la tierra. Las pr\u00e1cticas culturales nos arraigan en la tierra, incluso cuando estamos mirando hacia el cielo.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no15\">\n<div class=\"innerBox\">Naturaleza<\/div>\n<div class=\"onHover-display\">Adentrarte en la <b>naturaleza<\/b> y participar en actividades al aire libre te pueden proporcionar un poderoso medio para disminuir la ansiedad, la depresi\u00f3n y el estr\u00e9s, y aumentar tu capacidad de establecer relaciones. Yo utilizo muchas de las medicinas de la naturaleza para apoyar tu capacidad innata de sanar.\n<\/div>\n<\/div>\n\n<div class=\"innerSection no16\">\n<div class=\"innerBox\">Ritmos Biol\u00f3gicos \/ Hormonas<\/div>\n<div class=\"onHover-display\">La depresi\u00f3n, el trastorno bipolar, el trastorno de estr\u00e9s postraum\u00e1tico, el TDAH y el insomnio est\u00e1n relacionados con una alteraci\u00f3n de los <b>ritmos biol\u00f3gicos y las hormonas.<\/b> Cuando volvemos a equilibrar estos ritmos innatos de forma natural, podemos mejorar tu estado de \u00e1nimo y reconstruir tu salud desde la base.\n\n <\/div>\n<\/div>\n\n<div class=\"innerSection no17\">\n<div class=\"innerBox\">Evaluaci\u00f3n Integrativa<\/div>\n<div class=\"onHover-display\">La <b>evaluaci\u00f3n integrativa<\/b> me permite unir las piezas del rompecabezas para ver la historia completa de tu salud. Esta incluye un amplio historial f\u00edsico, emocional, cognitivo y traum\u00e1tico, y puede incluir diversos estudios funcionales de laboratorio.\n.<\/div>\n<\/div>\n\n<div class=\"seeAll\"><a>Ver todo<\/a><\/div>\n\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull brainbow-content-sec\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h1 class=\"wp-block-heading main-head\" id=\"h-un-enfoque-de-espectro-completo-de-la-salud-y-la-sanacion\">Un enfoque de espectro completo de la salud y la sanaci\u00f3n<\/h1>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"content-fnt-wt\" style=\"font-size:24px\">Viniste al mundo con una capacidad natural para integrar tus experiencias, y eso incluye una capacidad innata para sanar.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"subhead\">Al nacer en el mundo moderno, tus experiencias educativas y la especializaci\u00f3n profesional hacia la que gravitaste han reforzado formas de percibir el mundo (y a ti mismo) en las que, con toda naturalidad, has perdido <strong>cierto grado de contacto con estas capacidades.<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading inner-head\">Hay formas de reconectar tu capacidad innata de sanar<\/h2>\n\n\n\n<p class=\"subhead\">Como la mayor\u00eda de la gente, probablemente tambi\u00e9n hayas experimentado c\u00f3mo el trauma y la enfermedad se suman a la desconexi\u00f3n que experimentan tu cuerpo, mente y esp\u00edritu y estiran a\u00fan m\u00e1s tu \u00abancho de banda\u00bb.<\/p>\n\n\n\n<p class=\"subhead\">Pero tras haber pasado 45 a\u00f1os desarrollando el campo de la medicina integrativa para la salud mental, he descubierto que, por muy mal que te sientas, hay formas de volver a conectar con tu capacidad innata de sanar y mejorar tu salud f\u00edsica, mental y emocional.<\/p>\n\n\n\n<p class=\"subhead\">Para permitir que se produzca una sanaci\u00f3n profunda (en lugar de limitarse a la supresi\u00f3n de los s\u00edntomas), tus m\u00e9dicos deben <strong>adoptar un enfoque<\/strong> que te trate como una persona completa y restablezca tu capacidad de curaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull brainbow-image-content-sec has-background\" style=\"background-color:#eae1d5\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"657\" height=\"1024\" src=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg\" alt=\"\" class=\"wp-image-33167\" srcset=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg 657w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-335x522.jpg 335w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-768x1197.jpg 768w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-985x1536.jpg 985w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-1314x2048.jpg 1314w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-scaled.jpg 1642w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center right-col is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading head\" id=\"h-un-enfoque-individualizado\">Un enfoque individualizado<\/h2>\n\n\n\n<p class=\"subhead\">Mis d\u00e9cadas de experiencia cl\u00ednica e investigaci\u00f3n me han permitido crear un enfoque integral e individualizado que te ayuda a experimentar la restauraci\u00f3n de tu potencial para sanar.<\/p>\n\n\n\n<p class=\"subhead\">Siguiendo mi enfoque, conseguir\u00e1s de forma natural<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Equilibrar tu estado de \u00e1nimo<\/strong><\/li>\n\n\n\n<li><strong>Mejorar el sue\u00f1o<\/strong><\/li>\n\n\n\n<li><strong>Aumentar tu energ\u00eda<\/strong><\/li>\n\n\n\n<li><strong>Disminuir o eliminar la necesidad de medicamentos<\/strong><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group brainbow-content-sec2\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading main-heading\" id=\"h-siguiendo-el-modelo-del-arcoiris-del-cerebro\">Siguiendo el Modelo del arcoiris del cerebro<sup>\u00ae<\/sup><\/h2>\n\n\n\n<p class=\"subhead\">Llamo a mi enfoque El Modelo del arcoiris del cerebro<sup>\u00ae<\/sup>.<\/p>\n\n\n\n<p class=\"subhead\">Igual que nutrimos mejor nuestro cuerpo comiendo alimentos de todos los colores, el Modelo del arcoiris del cerebro contiene toda una gama de opciones de tratamiento natural que armonizan entre s\u00ed y con otros m\u00e9todos.<\/p>\n\n\n\n<p class=\"subhead\">Adapto este modelo a tus necesidades bioindividuales, colaborando contigo en cada paso para optimizar su eficacia y asegurarme de que puedas realizar los cambios que deseas en tu vida diaria.<\/p>\n\n\n\n<p class=\"subhead\">Utilizo el Modelo del arcoiris del cerebro para tratar con \u00e9xito traumas complejos, trastorno de estr\u00e9s postraum\u00e1tico, depresi\u00f3n, ansiedad, adicci\u00f3n, dolor cr\u00f3nico, TOC, TDAH, insomnio y trastornos autoinmunes y digestivos.<\/p>\n\n\n\n<p class=\"subhead\">\u00bfEres un profesional de la salud? <strong><a href=\"\/es\/courses\/\">Aprende a utilizar mi Modelo del arcoiris del cerebro<sup>\u00ae<\/sup> con tus clientes<\/a><\/strong><\/p>\n\n\n\n<p class=\"subhead\">Reserva una <strong><a href=\"https:\/\/drlesliekorn.com\/es\/trabaja-conmigo\/consulta-de-salud\/\">Consulta de salud<\/a><\/strong><\/p>\n\n\n\n<p>Lee mi nuevo libro <strong><em><a href=\"https:\/\/drlesliekorn.com\/es\/libros\/el-modelo-del-arcoiris-del-cerebro-una-guia-clinica-de-medicina-integral-y-nutricion\/\">The Brainbow Blueprint: A Clinical Guide to Integrative Medicine and Nutrition for Mental Well-Being<\/a><\/em><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull image-section\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image alignfull size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/brainbow-blueprint-nutrition-1024x683.webp\" alt=\"\" class=\"wp-image-35369\" srcset=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/brainbow-blueprint-nutrition-1024x683.webp 1024w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/brainbow-blueprint-nutrition-784x522.webp 784w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/brainbow-blueprint-nutrition-768x512.webp 768w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/brainbow-blueprint-nutrition-1536x1024.webp 1536w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/brainbow-blueprint-nutrition-2048x1365.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull brainbow-content-sec2 pd-btm has-background\" style=\"background-color:#eae1d5\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading main-heading\" id=\"h-como-funciona-el-modelo-del-arcoiris-del-cerebro\">C\u00f3mo funciona el Modelo del arcoiris del cerebro<sup>\u00ae<\/sup><\/h2>\n\n\n\n<p class=\"subhead\">Una de las piedras angulares de la medicina integrativa es el hecho de que la psique (nuestra mente-esp\u00edritu) y el soma (nuestro cuerpo) son dos caras de una misma moneda.<\/p>\n\n\n\n<p class=\"subhead\">Trabajar con una cara sin la otra suele provocar efectos \u00absecundarios\u00bb, desequilibrios e incluso bloqueos de la curaci\u00f3n.<\/p>\n\n\n\n<p class=\"subhead\">A pesar de las promesas de muchos m\u00e9dicos entusiastas o defensores de dietas, no existe un enfoque \u00fanico para mejorar tu salud.<\/p>\n\n\n\n<p class=\"subhead\">Con el Modelo del arcoiris del cerebro<sup>\u00ae<\/sup>, empiezo utilizando pruebas gen\u00f3micas para ayudarte a comprender m\u00e1s profundamente qui\u00e9n eres a nivel biol\u00f3gico y c\u00f3mo podr\u00edas responder a todos los m\u00e9todos disponibles.<\/p>\n\n\n\n<p class=\"subhead\">La integraci\u00f3n que experimentas es mayor que la que se suele incluir en la medicina integrativa, porque el Modelo del arcoiris del cerebro<sup>\u00ae<\/sup> incluye la bioindividualidad, consideraciones culturales y \u00e9tnicas, medicina culinaria y herbolaria, trabajo corporal, espiritualidad y b\u00fasqueda de significado, entre 16 \u00e1reas diferentes que puedes elegir e incorporar.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/drlesliekorn.com\/es\/trabaja-conmigo\/consulta-de-salud\/#jill-embarked\">Descubre lo que ocurri\u00f3 cuando mi clienta Jill se embarc\u00f3 en el M\u00e9todo del arcoiris del cerebro<sup>\u00ae<\/sup>.<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group brainbow-content-sec2\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading main-heading\" id=\"h-un-mapa-flexible\">Un mapa flexible<\/h2>\n\n\n\n<p class=\"subhead\">Con el Modelo del arcoiris del cerebro<sup>\u00ae<\/sup> te proporciono un mapa flexible, ajustable y accesible para todos. Pueden utilizarla tanto los practicantes principiantes de medicina integrativa como los profesionales que se encuentran en fases avanzadas de su pr\u00e1ctica.<\/p>\n\n\n\n<p class=\"subhead\">El Modelo del arcoiris del cerebro<sup>\u00ae<\/sup> incluye un componente educativo que te ayuda a formar un equipo con tus proveedores de atenci\u00f3n m\u00e9dica, a medida que descubres tus necesidades \u00fanicas, empoder\u00e1ndote a lo largo del camino y aumentando tu satisfacci\u00f3n con el tratamiento.<\/p>\n\n\n\n<p class=\"subhead\"><strong><a href=\"\/es\/courses\/\">Aprende a utilizar mi Modelo del arcoiris del cerebro<sup>\u00ae<\/sup> con tus clientes<\/a><\/strong><\/p>\n\n\n\n<p class=\"subhead\">Reserva una <strong><a href=\"https:\/\/drlesliekorn.com\/es\/trabaja-conmigo\/consulta-de-salud\/\">Consulta de salud<\/a><\/strong><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Modelo del arcoiris del cerebro Bioindividualidad Teniendo en cuenta tu bioindividualidad, analizo tu biolog\u00eda, tu gen\u00f3mica y el entorno ambiental y cultural que han conformado tu salud, para as\u00ed [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"parent":37748,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_genesis_hide_title":true,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"brainbow-page","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":{"0":"post-37755","1":"page","2":"type-page","3":"status-publish","5":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Modelo del arcoiris del cerebrot\u00ae de la Dra. Leslie Korn<\/title>\n<meta name=\"description\" content=\"Brainbow Blueprint culmina 40 a\u00f1os de investigaci\u00f3n y pr\u00e1ctica cl\u00ednica y proporciona un enfoque de espectro completo para la salud y la curaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plano de Brainbow | Dr. Leslie Korn\" \/>\n<meta property=\"og:description\" content=\"El Modelo del arcoiris del cerebro Bioindividualidad Teniendo en cuenta tu bioindividualidad, analizo tu biolog\u00eda, tu gen\u00f3mica y el entorno ambiental y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr. Leslie Korn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/drlesliekorn1\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-10T12:31:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/modelo-arcoiris-cerebro\\\/\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/modelo-arcoiris-cerebro\\\/\",\"name\":\"El Modelo del arcoiris del cerebrot\u00ae de la Dra. Leslie Korn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/modelo-arcoiris-cerebro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/modelo-arcoiris-cerebro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg\",\"datePublished\":\"2022-07-21T09:10:22+00:00\",\"dateModified\":\"2025-01-10T12:31:42+00:00\",\"description\":\"Brainbow Blueprint culmina 40 a\u00f1os de investigaci\u00f3n y pr\u00e1ctica cl\u00ednica y proporciona un enfoque de espectro completo para la salud y la curaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/modelo-arcoiris-cerebro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/modelo-arcoiris-cerebro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/modelo-arcoiris-cerebro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/modelo-arcoiris-cerebro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acerca de m\u00ed\",\"item\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/acerca-de-mi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plano de Brainbow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#website\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/\",\"name\":\"Dr. Leslie Korn\",\"description\":\"Integrative Medicine with Heart\",\"publisher\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drlesliekorn.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\",\"name\":\"Leslie Korn, PhD, MPH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"contentUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"width\":2015,\"height\":1912,\"caption\":\"Leslie Korn, PhD, MPH\"},\"logo\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\"},\"description\":\"Leslie Korn, PhD, MPH, is a Doctor of Behavioral Medicine and a pioneer in natural and integrative medicine for mental health and chronic illness. She is the author of 10 books and the developer of the Brainbow Blueprint\u00ae model. She served as a Fulbright scholar on traditional medicine, a Clinical Fellow at Harvard Medical School, and a National Institutes of Health-funded research scientist in mind\\\/body medicine.\",\"sameAs\":[\"https:\\\/\\\/drlesliekorn.com\",\"https:\\\/\\\/www.facebook.com\\\/drlesliekorn1\",\"https:\\\/\\\/www.instagram.com\\\/dr.lesliekorn\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/dr-leslie-korn-5455135\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Modelo del arcoiris del cerebrot\u00ae de la Dra. Leslie Korn","description":"Brainbow Blueprint culmina 40 a\u00f1os de investigaci\u00f3n y pr\u00e1ctica cl\u00ednica y proporciona un enfoque de espectro completo para la salud y la curaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/","og_locale":"es_ES","og_type":"article","og_title":"Plano de Brainbow | Dr. Leslie Korn","og_description":"El Modelo del arcoiris del cerebro Bioindividualidad Teniendo en cuenta tu bioindividualidad, analizo tu biolog\u00eda, tu gen\u00f3mica y el entorno ambiental y","og_url":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/","og_site_name":"Dr. Leslie Korn","article_publisher":"https:\/\/www.facebook.com\/drlesliekorn1","article_modified_time":"2025-01-10T12:31:42+00:00","og_image":[{"url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/","url":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/","name":"El Modelo del arcoiris del cerebrot\u00ae de la Dra. Leslie Korn","isPartOf":{"@id":"https:\/\/drlesliekorn.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/#primaryimage"},"image":{"@id":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/#primaryimage"},"thumbnailUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg","datePublished":"2022-07-21T09:10:22+00:00","dateModified":"2025-01-10T12:31:42+00:00","description":"Brainbow Blueprint culmina 40 a\u00f1os de investigaci\u00f3n y pr\u00e1ctica cl\u00ednica y proporciona un enfoque de espectro completo para la salud y la curaci\u00f3n.","breadcrumb":{"@id":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/#primaryimage","url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg","contentUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/07\/dr-leslie-korn-brainbow-blueprint-min-1-657x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/modelo-arcoiris-cerebro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acerca de m\u00ed","item":"https:\/\/drlesliekorn.com\/es\/acerca-de-mi\/"},{"@type":"ListItem","position":2,"name":"Plano de Brainbow"}]},{"@type":"WebSite","@id":"https:\/\/drlesliekorn.com\/#website","url":"https:\/\/drlesliekorn.com\/","name":"Dr. Leslie Korn","description":"Integrative Medicine with Heart","publisher":{"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drlesliekorn.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d","name":"Leslie Korn, PhD, MPH","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","contentUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","width":2015,"height":1912,"caption":"Leslie Korn, PhD, MPH"},"logo":{"@id":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png"},"description":"Leslie Korn, PhD, MPH, is a Doctor of Behavioral Medicine and a pioneer in natural and integrative medicine for mental health and chronic illness. She is the author of 10 books and the developer of the Brainbow Blueprint\u00ae model. She served as a Fulbright scholar on traditional medicine, a Clinical Fellow at Harvard Medical School, and a National Institutes of Health-funded research scientist in mind\/body medicine.","sameAs":["https:\/\/drlesliekorn.com","https:\/\/www.facebook.com\/drlesliekorn1","https:\/\/www.instagram.com\/dr.lesliekorn\/?hl=en","https:\/\/www.linkedin.com\/in\/dr-leslie-korn-5455135"]}]}},"_links":{"self":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/pages\/37755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/comments?post=37755"}],"version-history":[{"count":0,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/pages\/37755\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/pages\/37748"}],"wp:attachment":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/media?parent=37755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}