{"id":37770,"date":"2022-10-05T14:41:51","date_gmt":"2022-10-05T14:41:51","guid":{"rendered":"https:\/\/drlesliekorn.com\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/"},"modified":"2023-07-06T06:29:19","modified_gmt":"2023-07-06T06:29:19","slug":"prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa","status":"publish","type":"page","link":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/","title":{"rendered":"Prevenir y tratar la diabetes de forma natural: La manera nativa"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull k-home-sec has-background\" style=\"background-color:#eae1d5\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column book-banner-left-clm is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">\u00abUno de los enfoques m\u00e1s progresistas, exhaustivos e interesantes\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-center lila-md wp-block-paragraph\"><br><strong><strong>Eleanora Lipton, CMT, RPE<\/strong><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center chair-para wp-block-paragraph\">Fundadora y codirectora del Atlanta Polarity Center<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column nutr-sec-clm is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"1024\" src=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp\" alt=\"\" class=\"wp-image-35303\" srcset=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp 709w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-362x522.webp 362w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-768x1109.webp 768w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn.webp 800w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column book-banner-right-clm is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center an-pera wp-block-paragraph\" id=\"h-an-invaluable-resource\">\u00ab\u00a1Una vez que empec\u00e9 a leer no pude dejarlo!\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-center jem-hed wp-block-paragraph\"><strong><strong><strong>Diana Thompson, LMP<\/strong><\/strong><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center intgrat-pera wp-block-paragraph\">Presidenta, Fundaci\u00f3n Americana de Terapia de Masaje<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull k-home-2nd-sec has-background\" style=\"background-color:#faf5ee\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:150px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" id=\"h-prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\">Prevenir y tratar la diabetes de forma natural: La manera nativa<\/h1>\n\n\n\n<p class=\"book-pera wp-block-paragraph\">\u00bfSab\u00edas que&#8230;<br>La c\u00e1scara de psilio reduce los niveles de glucosa en sangre?<br>Los ar\u00e1ndanos contienen antocianidinas, un potente antioxidante que protege contra la neuropat\u00eda?<br>Para calcular la cantidad de agua diaria que necesitas, divide tu peso por la mitad y bebe esa cantidad en onzas?<br>Las personas con diabetes est\u00e1n m\u00e1s sanas cuando eliminan el trigo de su dieta?<\/p>\n\n\n\n<p class=\"sixWidth-para wp-block-paragraph\">Este libro ofrece un enfoque hol\u00edstico de la prevenci\u00f3n y el tratamiento, integrando las tradiciones curativas ind\u00edgenas americanas del noroeste del Pac\u00edfico con la medicina complementaria\/alternativa. Los cap\u00edtulos especiales incluyen el trauma hist\u00f3rico, el masaje y la terapia de polaridad para la neuropat\u00eda, los suplementos nutricionales eficaces, las hierbas y la interacci\u00f3n hierba-nutriente con los f\u00e1rmacos.<\/p>\n\n\n\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column cet-cta-sec has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#eae1d5\">\n<h3 class=\"wp-block-heading has-text-align-center book-head\" id=\"h-obten-tu-copia-de-preventing-and-treating-diabetes-naturally\">Obt\u00e9n tu copia de Preventing and Treating Diabetes Naturally<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.amazon.com\/Preventing-Treating-Diabetes-Naturally-Leslie\/dp\/0557068215\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amazon<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns thing-book-clm is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center book-head\" id=\"h-lo-que-te-ensenara-este-libro\">Lo qu\u00e9 te ense\u00f1ar\u00e1 este libro<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" id=\"h-learn-how-to\"><em><em>Aprender\u00e1s&#8230;<\/em><\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Protocolos nutricionales espec\u00edficos para prevenir y tratar la diabetes tipo 2<\/li>\n\n\n\n<li>Por qu\u00e9 no hay una dieta para todos<\/li>\n\n\n\n<li>M\u00e9todos paso a paso que incluyen la ciencia de la medicina natural<\/li>\n\n\n\n<li>El trauma hist\u00f3rico y su influencia en la diabetes entre los pueblos ind\u00edgenas del noroeste del Pac\u00edfico<\/li>\n\n\n\n<li>Intervenciones herbarias para reducir el az\u00facar en sangre<\/li>\n\n\n\n<li>Ejercicios para mejorar la captaci\u00f3n de insulina<\/li>\n\n\n\n<li>Protocolos para tratar la neuropat\u00eda<\/li>\n\n\n\n<li>C\u00f3mo crear un programa asequible de alimentos integrales<\/li>\n\n\n\n<li>C\u00f3mo organizar a la comunidad para mejorar la salud con alimentos<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" id=\"h-learn-how-to\"><em>Y mucho m\u00e1s\u2026<\/em><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group praise-sec\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center pra-head\" id=\"h-testimonios\">Testimonios<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column praise-first-clm has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#faf5ee\">\n<p class=\"wp-block-paragraph\">\u00abLeyendo este libro como profesional sanitario, consultor de investigaci\u00f3n y persona que vive con diabetes, no s\u00f3lo me siento escuchado, sino que me siento mejor preparado para actuar en mi vida y con mis clientes. Una vez que empec\u00e9 a leerlo, \u00a1no pude dejarlo! Gracias por hacer que las decisiones saludables tengan sentido\u00bb.<\/p>\n\n\n\n<div class=\"aut-bio-c-sec\">\n    <div class=\"left-sec\">\n        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/12\/Diana-Thompsom.png\"\/>\n    <\/div>    \n    <div class=\"right-sec\">\n        <p class=\"title\">Diana Thompson, LMP<\/p>\n        <p class=\"sh-des\">Presidenta, Fundaci\u00f3n Americana de Terapia de Masaje<\/p>\n    <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column praise-first-clm has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#faf5ee\">\n<p class=\"wp-block-paragraph\">\u00abEste libro proporciona uno de los enfoques m\u00e1s progresistas, exhaustivos e interesantes para comprender el proceso de curaci\u00f3n\/enfermedad que he le\u00eddo nunca. El an\u00e1lisis y los m\u00e9todos de este libro llegan al siguiente nivel de c\u00f3mo se define la curaci\u00f3n hol\u00edstica.\u00bb<\/p>\n\n\n\n<div class=\"aut-bio-c-sec\">\n    <div class=\"left-sec\">\n        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/12\/Eleanora-Lipton.png\"\/>\n    <\/div>    \n    <div class=\"right-sec\">\n        <p class=\"title\">Eleanora Lipton, CMT, RPE<\/p>\n        <p class=\"sh-des\">Fundadora y codirectora del Atlanta Polarity Center<\/p>\n    <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background\" style=\"background-color:#eae1d5\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns alignfull full-clm-get-cta-sec is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column cet-cta-sec has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#eae1d5\">\n<h3 class=\"wp-block-heading has-text-align-center book-head\" id=\"h-obten-tu-copia-de-preventing-and-treating-diabetes-naturally-1\">Obt\u00e9n tu copia de Preventing and Treating Diabetes Naturally<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.amazon.com\/Preventing-Treating-Diabetes-Naturally-Leslie\/dp\/0557068215\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amazon<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light nutr-bg-cv-sec\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"wp-block-cover__image-background wp-image-35305\" alt=\"\" src=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-type-2-naturally-roselle-scaled.webp\" data-object-fit=\"cover\" srcset=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-type-2-naturally-roselle-scaled.webp 2560w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-type-2-naturally-roselle-784x522.webp 784w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-type-2-naturally-roselle-1024x683.webp 1024w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-type-2-naturally-roselle-768x512.webp 768w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-type-2-naturally-roselle-1536x1024.webp 1536w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-type-2-naturally-roselle-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\"><div class=\"wp-block-image nurtr-ab\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"1024\" src=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp\" alt=\"\" class=\"wp-image-35303\" srcset=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp 709w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-362x522.webp 362w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-768x1109.webp 768w, https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn.webp 800w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull let-me-sec-grp has-background\" style=\"background-color:#faf5ee\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading head\" id=\"h-dejame-que-te-cuente-mas-cosas-sobre-el-libro\">D\u00e9jame que te cuente m\u00e1s cosas sobre el libro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Prevenir y tratar la diabetes de forma natural<\/em> es una obra que ha evolucionado a lo largo de 30 a\u00f1os de experiencia pr\u00e1ctica e investigaci\u00f3n. Durante m\u00e1s de 30 a\u00f1os, la Dra. Leslie Korn ha dirigido el Centro de Medicina Tradicional, un centro de medicina natural de salud p\u00fablica, que trabaja en comunidades rurales y urbanas practicando la Medicina Integrativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Formada tanto en salud f\u00edsica como en salud mental, ha sido testigo de las poderosas relaciones entre la diabetes, el estr\u00e9s cr\u00f3nico, el trauma y el dolor. Tambi\u00e9n ha guiado a decenas de miles de pacientes hacia la salud y el bienestar utilizando la medicina natural.<\/p>\n\n\n\n<p class=\"reed-m moreless-button wp-block-paragraph\"><a href=\"#\"><strong><strong>Sigue leyendo<\/strong><\/strong><\/a><\/p>\n\n\n\n<div class=\"wp-block-group moretext removedpadding\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">El Dr. Rudolph R\u00ffser es un l\u00edder que ha trabajado en Asuntos Indios desde 1970, formulando leyes y pol\u00edticas tribales de salud y recursos naturales en Estados Unidos, Canad\u00e1, Australia y Nicaragua, y ha trabajado internacionalmente en las Naciones Unidas asesorando y organiz\u00e1ndose con naciones indias y otras naciones ind\u00edgenas para restablecer el autogobierno y las pr\u00e1cticas culturales con el fin de mejorar la salud y el bienestar de la comunidad. Tambi\u00e9n es cocinero de alimentos tradicionales y naturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSe est\u00e1n reuniendo una vez m\u00e1s, para recordar la sabidur\u00eda de los ancianos, contar historias, encontrar los antiguos lugares ocultos donde a\u00fan crecen las camas y preparar y compartir sus alimentos con los dem\u00e1s\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juntos, el Dr. Korn y la Dra. R\u00ffser desarrollaron y presentaron docenas de talleres diferentes sobre salud y pol\u00edtica, incluyendo siempre un componente de comida sana que reflejaba los alimentos aut\u00e9nticos y las tradiciones culturales de la regi\u00f3n concreta. Inevitablemente, a todo el mundo le encantaba reunir comida, estar en la cocina y compartir historias sobre su alimentaci\u00f3n y dieta. Muchos de estos talleres constituyen la base de este libro y programa de formaci\u00f3n. Estas experiencias condujeron al m\u00e9todo que Korn y R\u00ffser denominan \u00abpedagog\u00eda culinaria\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9ste da prioridad a las ense\u00f1anzas compartidas sobre medicina, nutrici\u00f3n y curaci\u00f3n (y a la intersecci\u00f3n de la pol\u00edtica y la historia) mediante m\u00e9todos pr\u00e1cticos como la recolecci\u00f3n, la preparaci\u00f3n y el intercambio de comidas y medicinas de las \u00abbibliotecas\u00bb del bosque, la tierra y el oc\u00e9ano. Ir\u00f3nicamente, \u00e9stos son y han sido los comportamientos naturales de muchas comunidades durante milenios que, en gran parte, se han perdido, y ahora esperan su resurgimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. R\u00ffser se vio profundamente influido por su madre, una curandera que le ense\u00f1\u00f3 los m\u00e9todos de los pueblos taidnepum y los alimentos de los pueblos salish, incluso mientras soportaban los productos de mala calidad, como la leche en polvo, el cuatro blanco y la carne de vacuno enlatada, disponibles como productos excedentarios. Las experiencias de la Dra. Korn de trabajar durante 25 a\u00f1os en una remota comunidad ind\u00edgena de la selva donde no hab\u00eda m\u00e9dico, as\u00ed como durante muchos a\u00f1os en la \u00abselva urbana\u00bb de Boston, le permitieron probar todos estos m\u00e9todos en s\u00ed misma y en sus pacientes de diversas comunidades y adaptar estos principios a diversos entornos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para las familias y los pacientes, este libro es una herramienta de referencia, que puede revisarse en muchas ocasiones. Puede abrirse en cualquier momento. Para el profesional sanitario, este libro es tambi\u00e9n una herramienta de consulta, con secciones del libro que pueden imprimirse y utilizarse durante los talleres o para el tratamiento y la educaci\u00f3n de las personas con diabetes, sus familias y sus profesionales sanitarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este libro y el programa educativo est\u00e1n dise\u00f1ados para servir de punto de partida a todas las comunidades y familias que deseen a\u00f1adir, quitar o ajustar las ideas, recetas y protocolos que aqu\u00ed se presentan para que sean adecuados a su salud individual y a las necesidades de sus familias y comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Recuerda! No es necesario que tengas diabetes para beneficiarte de las ideas y recetas de este libro. \u00a1Este libro te mantendr\u00e1 sano y feliz!<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center head abt\" id=\"h-acerca-de-leslie-korn\">Acerca de Leslie Korn<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Dra. Leslie Korn ejerce la pr\u00e1ctica cl\u00ednica en dos idiomas y dos pa\u00edses desde 1977. Ha impartido clases de asesoramiento multicultural en el Instituto de Estudios Integrales de California, la Universidad Capella y la Universidad Lesley. Ha trabajado como directora de investigaci\u00f3n y educaci\u00f3n en cwis.org, una organizaci\u00f3n ind\u00edgena sin \u00e1nimo de lucro desde 1996.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background\" style=\"background-color:#eae1d5\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns alignfull full-clm-get-cta-sec is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column cet-cta-sec has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#eae1d5\">\n<h3 class=\"wp-block-heading has-text-align-center book-head\" id=\"h-obten-tu-copia-de-preventing-and-treating-diabetes-naturally-2\">Obt\u00e9n tu copia de Preventing and Treating Diabetes Naturally<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.amazon.com\/Preventing-Treating-Diabetes-Naturally-Leslie\/dp\/0557068215\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amazon<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00abUno de los enfoques m\u00e1s progresistas, exhaustivos e interesantes\u00bb. Eleanora Lipton, CMT, RPE Fundadora y codirectora del Atlanta Polarity Center \u00ab\u00a1Una vez que empec\u00e9 a leer no pude dejarlo!\u00bb. Diana [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"parent":37763,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_genesis_hide_title":true,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":["post-37770","page","type-page","status-publish","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prevenir y tratar la diabetes de forma natural: La manera nativa<\/title>\n<meta name=\"description\" content=\"Este libro, que previene y trata la diabetes, integra las tradiciones curativas de los ind\u00edgenas del Pac\u00edfico Noroeste de los Estados Unidos con la medicina complementaria\/alternativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prevenir y tratar la diabetes de forma natural: La manera nativa | Dr. Leslie Korn\" \/>\n<meta property=\"og:description\" content=\"&quot;Uno de los enfoques m\u00e1s progresistas, exhaustivos e interesantes&quot;. Eleanora Lipton, CMT, RPE Fundadora y codirectora del Atlanta Polarity Center &quot;\u00a1Una\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr. Leslie Korn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/drlesliekorn1\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T06:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\\\/\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\\\/\",\"name\":\"Prevenir y tratar la diabetes de forma natural: La manera nativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp\",\"datePublished\":\"2022-10-05T14:41:51+00:00\",\"dateModified\":\"2023-07-06T06:29:19+00:00\",\"description\":\"Este libro, que previene y trata la diabetes, integra las tradiciones curativas de los ind\u00edgenas del Pac\u00edfico Noroeste de los Estados Unidos con la medicina complementaria\\\/alternativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp\",\"contentUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Libros\",\"item\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/libros\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prevenir y tratar la diabetes de forma natural: La manera nativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#website\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/\",\"name\":\"Dr. Leslie Korn\",\"description\":\"Integrative Medicine with Heart\",\"publisher\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drlesliekorn.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\",\"name\":\"Leslie Korn, PhD, MPH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"contentUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"width\":2015,\"height\":1912,\"caption\":\"Leslie Korn, PhD, MPH\"},\"logo\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\"},\"description\":\"Leslie Korn, PhD, MPH, is a Doctor of Behavioral Medicine and a pioneer in natural and integrative medicine for mental health and chronic illness. She is the author of 10 books and the developer of the Brainbow Blueprint\u00ae model. She served as a Fulbright scholar on traditional medicine, a Clinical Fellow at Harvard Medical School, and a National Institutes of Health-funded research scientist in mind\\\/body medicine.\",\"sameAs\":[\"https:\\\/\\\/drlesliekorn.com\",\"https:\\\/\\\/www.facebook.com\\\/drlesliekorn1\",\"https:\\\/\\\/www.instagram.com\\\/dr.lesliekorn\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/dr-leslie-korn-5455135\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prevenir y tratar la diabetes de forma natural: La manera nativa","description":"Este libro, que previene y trata la diabetes, integra las tradiciones curativas de los ind\u00edgenas del Pac\u00edfico Noroeste de los Estados Unidos con la medicina complementaria\/alternativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/","og_locale":"es_ES","og_type":"article","og_title":"Prevenir y tratar la diabetes de forma natural: La manera nativa | Dr. Leslie Korn","og_description":"\"Uno de los enfoques m\u00e1s progresistas, exhaustivos e interesantes\". Eleanora Lipton, CMT, RPE Fundadora y codirectora del Atlanta Polarity Center \"\u00a1Una","og_url":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/","og_site_name":"Dr. Leslie Korn","article_publisher":"https:\/\/www.facebook.com\/drlesliekorn1","article_modified_time":"2023-07-06T06:29:19+00:00","og_image":[{"url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/","url":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/","name":"Prevenir y tratar la diabetes de forma natural: La manera nativa","isPartOf":{"@id":"https:\/\/drlesliekorn.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/#primaryimage"},"image":{"@id":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/#primaryimage"},"thumbnailUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp","datePublished":"2022-10-05T14:41:51+00:00","dateModified":"2023-07-06T06:29:19+00:00","description":"Este libro, que previene y trata la diabetes, integra las tradiciones curativas de los ind\u00edgenas del Pac\u00edfico Noroeste de los Estados Unidos con la medicina complementaria\/alternativa.","breadcrumb":{"@id":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/#primaryimage","url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp","contentUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2023\/01\/preventing-and-treating-diabetes-naturally-the-native-way-dr-leslie-korn-709x1024.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/drlesliekorn.com\/es\/libros\/prevenir-y-tratar-la-diabetes-de-forma-natural-la-manera-nativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Libros","item":"https:\/\/drlesliekorn.com\/es\/libros\/"},{"@type":"ListItem","position":2,"name":"Prevenir y tratar la diabetes de forma natural: La manera nativa"}]},{"@type":"WebSite","@id":"https:\/\/drlesliekorn.com\/#website","url":"https:\/\/drlesliekorn.com\/","name":"Dr. Leslie Korn","description":"Integrative Medicine with Heart","publisher":{"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drlesliekorn.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d","name":"Leslie Korn, PhD, MPH","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","contentUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","width":2015,"height":1912,"caption":"Leslie Korn, PhD, MPH"},"logo":{"@id":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png"},"description":"Leslie Korn, PhD, MPH, is a Doctor of Behavioral Medicine and a pioneer in natural and integrative medicine for mental health and chronic illness. She is the author of 10 books and the developer of the Brainbow Blueprint\u00ae model. She served as a Fulbright scholar on traditional medicine, a Clinical Fellow at Harvard Medical School, and a National Institutes of Health-funded research scientist in mind\/body medicine.","sameAs":["https:\/\/drlesliekorn.com","https:\/\/www.facebook.com\/drlesliekorn1","https:\/\/www.instagram.com\/dr.lesliekorn\/?hl=en","https:\/\/www.linkedin.com\/in\/dr-leslie-korn-5455135"]}]}},"_links":{"self":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/pages\/37770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/comments?post=37770"}],"version-history":[{"count":0,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/pages\/37770\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/pages\/37763"}],"wp:attachment":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/media?parent=37770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}