{"id":37807,"date":"2022-01-04T12:45:25","date_gmt":"2022-01-04T18:45:25","guid":{"rendered":"https:\/\/drlesliekorn.com\/?p=37807"},"modified":"2023-09-28T06:54:17","modified_gmt":"2023-09-28T06:54:17","slug":"trauma-adiccion-al-azucar","status":"publish","type":"post","link":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/","title":{"rendered":"Comprender el trauma y la adicci\u00f3n al az\u00facar"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-comprender-la-adiccion-al-azucar-y-la-recuperacion-del-trauma\"><strong>Comprender la adicci\u00f3n al az\u00facar y la recuperaci\u00f3n del trauma<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El az\u00facar refinado es un alimento proinflamatorio. Contribuye y exacerba la inflamaci\u00f3n, el dolor y la depresi\u00f3n. A medida que trabajamos para resolver el trauma, la pieza que a menudo se olvida u omite es el papel que desempe\u00f1a el az\u00facar en la depresi\u00f3n, el estado de \u00e1nimo y el dolor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cortisol es una hormona del estr\u00e9s desregulada por los acontecimientos traum\u00e1ticos. Se encarga de elevar los niveles de az\u00facar en sangre para darnos la sensaci\u00f3n de energ\u00eda. Pero en respuesta a un trauma complejo, el cortisol suele estar bajo y no puede elevar esos niveles de az\u00facar en sangre. Esto suele provocar antojos de az\u00facar y, a su vez, comer mucho az\u00facar y carbohidratos refinados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el tiempo, esto da lugar a una glucemia inestable y a s\u00edntomas de irritabilidad, temblores o mareos. Esto se denomina hipoglucemia reactiva y es la causa de los altibajos que llamamos inestabilidad del estado de \u00e1nimo, cuando en realidad puede tratarse de un desequilibrio del az\u00facar en sangre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra ingesta de az\u00facar provoca inflamaci\u00f3n en el organismo. Podemos sentir o no esta combusti\u00f3n lenta. Si tenemos dolor, tenemos inflamaci\u00f3n, pero podemos tener inflamaci\u00f3n y no sentirla todav\u00eda como dolor. La inflamaci\u00f3n, a su vez, altera las citocinas y la funci\u00f3n inmunitaria y agota la serotonina y otros neurotransmisores. As\u00ed, el ciclo del estado de \u00e1nimo, la depresi\u00f3n y el dolor contin\u00faa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Renunciar al az\u00facar refinado no significa que no podamos disfrutar de la dulzura de la vida y de los alimentos; sigue leyendo para saber por qu\u00e9 y c\u00f3mo renunciar al az\u00facar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfPor qu\u00e9 no al az\u00facar?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El az\u00facar refinado de la ca\u00f1a de az\u00facar y de la remolacha agota las vitaminas B y los minerales de apoyo inmunitario, como el zinc. Las vitaminas B ayudan a la funci\u00f3n neurol\u00f3gica y nos mantienen tranquilos. El az\u00facar refinado contribuye a la depresi\u00f3n. En EEUU hay tanta gente que come az\u00facar refinado, que esto puede explicar los altos niveles de depresi\u00f3n, dolor y adicci\u00f3n a los opi\u00e1ceos. Exacerba el dolor y eleva los niveles de triglic\u00e9ridos y colesterol. El az\u00facar abruma al organismo al robarle nutrientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay varias alternativas buenas al az\u00facar y a los edulcorantes que no tienen los efectos secundarios de los edulcorantes artificiales, como el aspartame. Las personas con trastornos del estado de \u00e1nimo son susceptibles al aspartame, que empeora la depresi\u00f3n al alterar la funci\u00f3n cerebral.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Detener la adicci\u00f3n al az\u00facar<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seguir una dieta rica en prote\u00ednas durante 7-10 d\u00edas puede ayudar a dejar el az\u00facar y los carbohidratos refinados. Come peque\u00f1as cantidades (2-4 onzas) de prote\u00edna seis veces al d\u00eda (aproximadamente cada 3-4 horas) y una o dos raciones de un tub\u00e9rculo, como un camote o zanahorias cubiertas de mantequilla, aceite de coco o aceite de oliva, junto con ensaladas crudas o verduras verdes cocidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es necesario pasar hambre, as\u00ed que come con la frecuencia que necesites. Siguiendo este cambio de dieta, la mayor\u00eda de la gente perder\u00e1 el ansia por los carbohidratos refinados y los az\u00facares. Despu\u00e9s, a\u00f1ade cada d\u00eda a la dieta peque\u00f1as cantidades de carbohidratos adicionales, como fruta y cereales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sustitutos del az\u00facar<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La stevia es el sustituto ideal del az\u00facar. Es cien veces m\u00e1s dulce que el az\u00facar, lo que reduce el az\u00facar en sangre. Mientras que la forma en polvo de la stevia puede tender a dejar un gusto amargo, la forma l\u00edquida no. Util\u00edzala en bebidas o en la preparaci\u00f3n de alimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El xilitol es otro edulcorante sin efectos secundarios. Se extrajo por primera vez del abedul y proporciona un sabor dulce saludable que no eleva los niveles de glucosa en sangre ni afecta negativamente a la salud dental. Pero muchas personas experimentan una reacci\u00f3n a \u00e9l, como gases y molestias digestivas, y \u00a1ojo! es mortal para los perros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tabla de conversi\u00f3n stevia\/az\u00facar<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table sugarpost-table\"><table><tbody><tr><td><strong>Cantidad de az\u00facar<\/strong><strong><\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>Equivalente de extracto de stevia en polvo<\/strong><strong><\/strong><\/td><td><strong>Equivalente de concentrado l\u00edquido de stevia<\/strong><strong><\/strong><\/td><\/tr><tr><td>1 taza<\/td><td class=\"has-text-align-left\" data-align=\"left\">1 cucharadita<\/td><td>1 cucharadita (24-36 drops)<\/td><\/tr><tr><td>1 cucharada<\/td><td class=\"has-text-align-left\" data-align=\"left\">\u00bc cucharadita<\/td><td>6-9 gotas<\/td><\/tr><tr><td>1 cucharadita<\/td><td class=\"has-text-align-left\" data-align=\"left\">Una pizca a 1\/16 cucharadita<\/td><td>2-4 gotas<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Alternativas al az\u00facar<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los smoothies endulzados con stevia son una alternativa a las golosinas azucaradas.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El cacao en polvo sin az\u00facar con stevia\/los caramelos de chocolate caseros endulzados con stevia son alternativas al chocolate con az\u00facar.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La miel de abeja o de maple son alternativas al az\u00facar de ca\u00f1a.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El cacao caliente endulzado con stevia y crema batida natural es una alternativa a las barritas de chocolate con az\u00facar.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La fruta cruda es una alternativa a los c\u00f3cteles de fruta.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El jugo verde es una alternativa al jugo de fruta.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El agua mineral saborizada con fruta congelada y stevia es una alternativa a los refrescos.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El t\u00e9 de hierbas con hielo es una alternativa al t\u00e9 helado comercial.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El pl\u00e1tano macho es una excelente adici\u00f3n al repertorio de carbohidratos ricos en almid\u00f3n cuando se elimina el az\u00facar o el trigo de la dieta.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Sigue aprendiendo sobre el az\u00facar, c\u00f3mo afecta a nuestra salud y c\u00f3mo vencer con \u00e9xito la adicci\u00f3n al az\u00facar en mi curso en l\u00ednea m\u00e1s reciente:<a href=\"https:\/\/drlesliekorn.com\/courses\/integrative-medicine-nutrition-ptsd-complex-trauma\/\" target=\"_blank\" rel=\"noreferrer noopener\"> <strong>Medicina integrativa y nutrici\u00f3n para el trastorno de estr\u00e9s postraum\u00e1tico, el trauma complejo y el traumatismo craneoencef\u00e1lico<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que trabajamos para resolver el trauma, la pieza que a menudo se olvida o falta es c\u00f3mo el az\u00facar juega un papel en la depresi\u00f3n, el estado de \u00e1nimo y el dolor. El consumo de az\u00facar exacerba la inflamaci\u00f3n, el dolor y la depresi\u00f3n. Comprender y detener la adicci\u00f3n al az\u00facar es posible, y las alternativas al az\u00facar pueden brindar apoyo durante el proceso.<\/p>\n","protected":false},"author":3,"featured_media":37163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[1315,1318],"tags":[1341,1332,1335,1409,1279],"class_list":["post-37807","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nutricion-es","category-salud-mental-es-3","tag-addiction-es","tag-depresion-es-2","tag-inflamacion-es","tag-mood-es","tag-tept","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comprender el trauma y la adicci\u00f3n al az\u00facar | Dr. Leslie Korn<\/title>\n<meta name=\"description\" content=\"A medida que trabajamos para resolver el trauma, la pieza que a menudo se olvida o falta es c\u00f3mo el az\u00facar juega un papel en la depresi\u00f3n, el estado de \u00e1nimo y el dolor. El consumo de az\u00facar exacerba la inflamaci\u00f3n, el dolor y la depresi\u00f3n. Comprender y detener la adicci\u00f3n al az\u00facar es posible, y las alternativas al az\u00facar pueden brindar apoyo durante el proceso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprender el trauma y la adicci\u00f3n al az\u00facar\" \/>\n<meta property=\"og:description\" content=\"A medida que trabajamos para resolver el trauma, la pieza que a menudo se olvida o falta es c\u00f3mo el az\u00facar juega un papel en la depresi\u00f3n, el estado de \u00e1nimo y el dolor. El consumo de az\u00facar exacerba la inflamaci\u00f3n, el dolor y la depresi\u00f3n. Comprender y detener la adicci\u00f3n al az\u00facar es posible, y las alternativas al az\u00facar pueden brindar apoyo durante el proceso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr. Leslie Korn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/drlesliekorn1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/drlesliekorn1\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-04T18:45:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-28T06:54:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/11\/trauma-sugar-addiction.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"830\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leslie Korn, PhD, MPH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leslie Korn, PhD, MPH\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/\"},\"author\":{\"name\":\"Leslie Korn, PhD, MPH\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\"},\"headline\":\"Comprender el trauma y la adicci\u00f3n al az\u00facar\",\"datePublished\":\"2022-01-04T18:45:25+00:00\",\"dateModified\":\"2023-09-28T06:54:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/\"},\"wordCount\":970,\"publisher\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\"},\"image\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/trauma-sugar-addiction.jpg\",\"keywords\":[\"Addiction\",\"Depresi\u00f3n\",\"Inflamaci\u00f3n\",\"Mood\",\"TEPT\"],\"articleSection\":[\"Nutrici\u00f3n\",\"Salud mental\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/\",\"name\":\"Comprender el trauma y la adicci\u00f3n al az\u00facar | Dr. Leslie Korn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/trauma-sugar-addiction.jpg\",\"datePublished\":\"2022-01-04T18:45:25+00:00\",\"dateModified\":\"2023-09-28T06:54:17+00:00\",\"description\":\"A medida que trabajamos para resolver el trauma, la pieza que a menudo se olvida o falta es c\u00f3mo el az\u00facar juega un papel en la depresi\u00f3n, el estado de \u00e1nimo y el dolor. El consumo de az\u00facar exacerba la inflamaci\u00f3n, el dolor y la depresi\u00f3n. Comprender y detener la adicci\u00f3n al az\u00facar es posible, y las alternativas al az\u00facar pueden brindar apoyo durante el proceso.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/trauma-adiccion-al-azucar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/trauma-sugar-addiction.jpg\",\"contentUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/trauma-sugar-addiction.jpg\",\"width\":2500,\"height\":830,\"caption\":\"trauma-sugar-addiction\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#website\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/\",\"name\":\"Dr. Leslie Korn\",\"description\":\"Integrative Medicine with Heart\",\"publisher\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drlesliekorn.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\",\"name\":\"Leslie Korn, PhD, MPH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"contentUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"width\":2015,\"height\":1912,\"caption\":\"Leslie Korn, PhD, MPH\"},\"logo\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\"},\"description\":\"Leslie Korn, PhD, MPH, is a Doctor of Behavioral Medicine and a pioneer in natural and integrative medicine for mental health and chronic illness. She is the author of 10 books and the developer of the Brainbow Blueprint\u00ae model. She served as a Fulbright scholar on traditional medicine, a Clinical Fellow at Harvard Medical School, and a National Institutes of Health-funded research scientist in mind\\\/body medicine.\",\"sameAs\":[\"https:\\\/\\\/drlesliekorn.com\",\"https:\\\/\\\/www.facebook.com\\\/drlesliekorn1\",\"https:\\\/\\\/www.instagram.com\\\/dr.lesliekorn\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/dr-leslie-korn-5455135\"],\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/es\\\/blog\\\/author\\\/dr_leslie_korn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comprender el trauma y la adicci\u00f3n al az\u00facar | Dr. Leslie Korn","description":"A medida que trabajamos para resolver el trauma, la pieza que a menudo se olvida o falta es c\u00f3mo el az\u00facar juega un papel en la depresi\u00f3n, el estado de \u00e1nimo y el dolor. El consumo de az\u00facar exacerba la inflamaci\u00f3n, el dolor y la depresi\u00f3n. Comprender y detener la adicci\u00f3n al az\u00facar es posible, y las alternativas al az\u00facar pueden brindar apoyo durante el proceso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/","og_locale":"es_ES","og_type":"article","og_title":"Comprender el trauma y la adicci\u00f3n al az\u00facar","og_description":"A medida que trabajamos para resolver el trauma, la pieza que a menudo se olvida o falta es c\u00f3mo el az\u00facar juega un papel en la depresi\u00f3n, el estado de \u00e1nimo y el dolor. El consumo de az\u00facar exacerba la inflamaci\u00f3n, el dolor y la depresi\u00f3n. Comprender y detener la adicci\u00f3n al az\u00facar es posible, y las alternativas al az\u00facar pueden brindar apoyo durante el proceso.","og_url":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/","og_site_name":"Dr. Leslie Korn","article_publisher":"https:\/\/www.facebook.com\/drlesliekorn1","article_author":"https:\/\/www.facebook.com\/drlesliekorn1","article_published_time":"2022-01-04T18:45:25+00:00","article_modified_time":"2023-09-28T06:54:17+00:00","og_image":[{"width":2500,"height":830,"url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/11\/trauma-sugar-addiction.jpg","type":"image\/jpeg"}],"author":"Leslie Korn, PhD, MPH","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leslie Korn, PhD, MPH","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/#article","isPartOf":{"@id":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/"},"author":{"name":"Leslie Korn, PhD, MPH","@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d"},"headline":"Comprender el trauma y la adicci\u00f3n al az\u00facar","datePublished":"2022-01-04T18:45:25+00:00","dateModified":"2023-09-28T06:54:17+00:00","mainEntityOfPage":{"@id":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/"},"wordCount":970,"publisher":{"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d"},"image":{"@id":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/#primaryimage"},"thumbnailUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/11\/trauma-sugar-addiction.jpg","keywords":["Addiction","Depresi\u00f3n","Inflamaci\u00f3n","Mood","TEPT"],"articleSection":["Nutrici\u00f3n","Salud mental"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/","url":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/","name":"Comprender el trauma y la adicci\u00f3n al az\u00facar | Dr. Leslie Korn","isPartOf":{"@id":"https:\/\/drlesliekorn.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/#primaryimage"},"image":{"@id":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/#primaryimage"},"thumbnailUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/11\/trauma-sugar-addiction.jpg","datePublished":"2022-01-04T18:45:25+00:00","dateModified":"2023-09-28T06:54:17+00:00","description":"A medida que trabajamos para resolver el trauma, la pieza que a menudo se olvida o falta es c\u00f3mo el az\u00facar juega un papel en la depresi\u00f3n, el estado de \u00e1nimo y el dolor. El consumo de az\u00facar exacerba la inflamaci\u00f3n, el dolor y la depresi\u00f3n. Comprender y detener la adicci\u00f3n al az\u00facar es posible, y las alternativas al az\u00facar pueden brindar apoyo durante el proceso.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drlesliekorn.com\/es\/blog\/trauma-adiccion-al-azucar\/#primaryimage","url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/11\/trauma-sugar-addiction.jpg","contentUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/11\/trauma-sugar-addiction.jpg","width":2500,"height":830,"caption":"trauma-sugar-addiction"},{"@type":"WebSite","@id":"https:\/\/drlesliekorn.com\/#website","url":"https:\/\/drlesliekorn.com\/","name":"Dr. Leslie Korn","description":"Integrative Medicine with Heart","publisher":{"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drlesliekorn.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d","name":"Leslie Korn, PhD, MPH","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","contentUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","width":2015,"height":1912,"caption":"Leslie Korn, PhD, MPH"},"logo":{"@id":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png"},"description":"Leslie Korn, PhD, MPH, is a Doctor of Behavioral Medicine and a pioneer in natural and integrative medicine for mental health and chronic illness. She is the author of 10 books and the developer of the Brainbow Blueprint\u00ae model. She served as a Fulbright scholar on traditional medicine, a Clinical Fellow at Harvard Medical School, and a National Institutes of Health-funded research scientist in mind\/body medicine.","sameAs":["https:\/\/drlesliekorn.com","https:\/\/www.facebook.com\/drlesliekorn1","https:\/\/www.instagram.com\/dr.lesliekorn\/?hl=en","https:\/\/www.linkedin.com\/in\/dr-leslie-korn-5455135"],"url":"https:\/\/drlesliekorn.com\/es\/blog\/author\/dr_leslie_korn\/"}]}},"_links":{"self":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/posts\/37807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/comments?post=37807"}],"version-history":[{"count":0,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/posts\/37807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/media\/37163"}],"wp:attachment":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/media?parent=37807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/categories?post=37807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/tags?post=37807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}