{"id":1438,"count":2,"description":"","link":"https:\/\/drlesliekorn.com\/es\/blog\/tag\/licorice-es\/","name":"Licorice","slug":"licorice-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Licorice Archives | Dr. Leslie Korn<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Licorice Archives | Dr. Leslie Korn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drlesliekorn.com\/blog\/tag\/licorice\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr. Leslie Korn\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2024\/09\/dr-leslie-korn-logo-english.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"784\" \/>\n\t<meta property=\"og:image:height\" content=\"226\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/blog\\\/tag\\\/licorice\\\/\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/blog\\\/tag\\\/licorice\\\/\",\"name\":\"Licorice Archives | Dr. Leslie Korn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#website\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#website\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/\",\"name\":\"Dr. Leslie Korn\",\"description\":\"Integrative Medicine with Heart\",\"publisher\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drlesliekorn.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/#\\\/schema\\\/person\\\/5ccfb74a0c80a3e8905c14756907556d\",\"name\":\"Leslie Korn, PhD, MPH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"url\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"contentUrl\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\",\"width\":2015,\"height\":1912,\"caption\":\"Leslie Korn, PhD, MPH\"},\"logo\":{\"@id\":\"https:\\\/\\\/drlesliekorn.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/dr-leslie-korn-logo-color-v.png\"},\"description\":\"Leslie Korn, PhD, MPH, is a Doctor of Behavioral Medicine and a pioneer in natural and integrative medicine for mental health and chronic illness. She is the author of 10 books and the developer of the Brainbow Blueprint\u00ae model. She served as a Fulbright scholar on traditional medicine, a Clinical Fellow at Harvard Medical School, and a National Institutes of Health-funded research scientist in mind\\\/body medicine.\",\"sameAs\":[\"https:\\\/\\\/drlesliekorn.com\",\"https:\\\/\\\/www.facebook.com\\\/drlesliekorn1\",\"https:\\\/\\\/www.instagram.com\\\/dr.lesliekorn\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/dr-leslie-korn-5455135\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Licorice Archives | Dr. Leslie Korn","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Licorice Archives | Dr. Leslie Korn","og_url":"https:\/\/drlesliekorn.com\/blog\/tag\/licorice\/","og_site_name":"Dr. Leslie Korn","og_image":[{"width":784,"height":226,"url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2024\/09\/dr-leslie-korn-logo-english.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/drlesliekorn.com\/blog\/tag\/licorice\/","url":"https:\/\/drlesliekorn.com\/blog\/tag\/licorice\/","name":"Licorice Archives | Dr. Leslie Korn","isPartOf":{"@id":"https:\/\/drlesliekorn.com\/#website"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/drlesliekorn.com\/#website","url":"https:\/\/drlesliekorn.com\/","name":"Dr. Leslie Korn","description":"Integrative Medicine with Heart","publisher":{"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drlesliekorn.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/drlesliekorn.com\/#\/schema\/person\/5ccfb74a0c80a3e8905c14756907556d","name":"Leslie Korn, PhD, MPH","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","url":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","contentUrl":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png","width":2015,"height":1912,"caption":"Leslie Korn, PhD, MPH"},"logo":{"@id":"https:\/\/drlesliekorn.com\/wp-content\/uploads\/2022\/02\/dr-leslie-korn-logo-color-v.png"},"description":"Leslie Korn, PhD, MPH, is a Doctor of Behavioral Medicine and a pioneer in natural and integrative medicine for mental health and chronic illness. She is the author of 10 books and the developer of the Brainbow Blueprint\u00ae model. She served as a Fulbright scholar on traditional medicine, a Clinical Fellow at Harvard Medical School, and a National Institutes of Health-funded research scientist in mind\/body medicine.","sameAs":["https:\/\/drlesliekorn.com","https:\/\/www.facebook.com\/drlesliekorn1","https:\/\/www.instagram.com\/dr.lesliekorn\/?hl=en","https:\/\/www.linkedin.com\/in\/dr-leslie-korn-5455135"]}]}},"_links":{"self":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/tags\/1438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/posts?tags=1438"},{"href":"https:\/\/drlesliekorn.com\/es\/wp-json\/wp\/v2\/groups?tags=1438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}